{"id":16682,"date":"2023-08-02T09:18:53","date_gmt":"2023-08-02T08:18:53","guid":{"rendered":"https:\/\/suasesport.com\/?p=16682"},"modified":"2023-08-02T09:18:54","modified_gmt":"2023-08-02T08:18:54","slug":"denigres-se-proclama-campeon-de-las-12-horas-de-veteranos-de-acydma","status":"publish","type":"post","link":"https:\/\/suasesport.com\/es\/denigres-se-proclama-campeon-de-las-12-horas-de-veteranos-de-acydma\/","title":{"rendered":"Denigr\u00e9s se proclama campe\u00f3n de las 12 horas de veteranos de ACYDMA"},"content":{"rendered":"\n<p>Denigres se proclam\u00f3 campe\u00f3n de las 12 horas de veteranos de ACYDMA al ganar en la final a L. B\u00e0mbola en la pr\u00f3rroga (6-4). El partido estuvo muy disputado y que mantuvo la emoci\u00f3n hasta el final. El tiempo reglamentario finaliz\u00f3 con empate a cuatro por lo que se tuvo que jugar el tiempo extra para decidir qu\u00e9 equipo era el campe\u00f3n. En la pr\u00f3rroga Denigres estuvo m\u00e1s certero de cara a puerta y marc\u00f3 dos goles que le dieron el t\u00edtulo.&nbsp;<\/p>\n\n\n\n<p>El campeonato se celebr\u00f3 en La Xara el s\u00e1bado. Denigr\u00e9s lleg\u00f3 a la final al vencer en semifinales a La Xara por 2-0, mientras que B\u00e0mbola lo hizo al ganar a Piscinas Nacionales por 4-1.&nbsp;<\/p>\n\n\n\n<p>Una vez concluida la final se procedi\u00f3 a la entrega de trofeos por mediaci\u00f3n del presidente de ACYDMA, Alberto Portillo, y en representaci\u00f3n de l\u2019Ajuntament de La Xara, Ernesto Ferrer.&nbsp;<\/p>\n\n\n\n<p>CUADRO DE HONOR<\/p>\n\n\n\n<p>Campe\u00f3n: Denigr\u00e9s.&nbsp;<\/p>\n\n\n\n<p>Subcampe\u00f3n: L. B\u00e0mbola.&nbsp;<\/p>\n\n\n\n<p>Tercero: La Xara.&nbsp;<\/p>\n\n\n\n<p>Cuarto: Piscinas Nacionales.<\/p>\n\n\n\n<p>&#8211; Jugador m\u00e1ximo goleador: V\u00edctor C\u00e9spedes (L. B\u00e0mbola).<\/p>\n\n\n\n<p>&#8211; Equipo menos goleado: L. B\u00e0mbola. &nbsp;<\/p>\n\n\n\n<p>ASAMBLEA GENERAL DE ACYDMA&nbsp;<\/p>\n\n\n\n<p>Por otro lado, la Asociaci\u00f3n Cultural y Deportiva Marina Alta (ACYDMA) realizar\u00e1 la asamblea general ordinaria de 2023 el pr\u00f3ximo 10 de agosto. La asamblea se celebrar\u00e1 en la sede de la asociaci\u00f3n a las 19.30 horas en primera convocatoria y a las 20 horas en segunda.&nbsp;<\/p>\n\n\n\n<p>Cuatro son los puntos del orden del d\u00eda: Lectura y aprobaci\u00f3n, si procede, del acta anterior; estado de cuentas del ejercicio 2022-2023 y balance general; fecha de inscripciones de equipos a las diferentes competiciones; y el cuarto y \u00faltimo, ruegos y preguntas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"16672\" src=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8641-1024x768.jpg\" alt=\"\" class=\"wp-image-16672\" srcset=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8641-1024x768.jpg 1024w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8641-300x225.jpg 300w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8641-768x576.jpg 768w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8641-1536x1152.jpg 1536w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8641-1080x810.jpg 1080w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8641.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"16674\" src=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8643-1024x768.jpg\" alt=\"\" class=\"wp-image-16674\" srcset=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8643-1024x768.jpg 1024w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8643-300x225.jpg 300w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8643-768x576.jpg 768w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8643-1536x1152.jpg 1536w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8643-1080x810.jpg 1080w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8643.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"16676\" src=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8645-1024x768.jpg\" alt=\"\" class=\"wp-image-16676\" srcset=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8645-1024x768.jpg 1024w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8645-300x225.jpg 300w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8645-768x576.jpg 768w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8645-1536x1152.jpg 1536w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8645-1080x810.jpg 1080w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8645.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"16678\" src=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8642-1024x768.jpg\" alt=\"\" class=\"wp-image-16678\" srcset=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8642-1024x768.jpg 1024w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8642-300x225.jpg 300w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8642-768x576.jpg 768w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8642-1536x1152.jpg 1536w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8642-1080x810.jpg 1080w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8642.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"16680\" src=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8644-1024x768.jpg\" alt=\"\" class=\"wp-image-16680\" srcset=\"https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8644-1024x768.jpg 1024w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8644-300x225.jpg 300w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8644-768x576.jpg 768w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8644-1536x1152.jpg 1536w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8644-1080x810.jpg 1080w, https:\/\/suasesport.com\/wp-content\/uploads\/2023\/08\/IMG_8644.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Denigres se proclam\u00f3 campe\u00f3n de las 12 horas de veteranos de ACYDMA al ganar en la final a L. B\u00e0mbola en la pr\u00f3rroga (6-4). El partido estuvo muy disputado y que mantuvo la emoci\u00f3n hasta el final. El tiempo reglamentario finaliz\u00f3 con empate a cuatro por lo que se tuvo que jugar el tiempo extra&hellip; <a class=\"more-link\" href=\"https:\/\/suasesport.com\/es\/denigres-se-proclama-campeon-de-las-12-horas-de-veteranos-de-acydma\/\">Seguir leyendo <span class=\"screen-reader-text\">Denigr\u00e9s se proclama campe\u00f3n de las 12 horas de veteranos de ACYDMA<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":16670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-16682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-f-sala","entry"],"_links":{"self":[{"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/posts\/16682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/comments?post=16682"}],"version-history":[{"count":4,"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/posts\/16682\/revisions"}],"predecessor-version":[{"id":16691,"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/posts\/16682\/revisions\/16691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/media\/16670"}],"wp:attachment":[{"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/media?parent=16682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/categories?post=16682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suasesport.com\/es\/wp-json\/wp\/v2\/tags?post=16682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}